{"id":26234,"date":"2023-04-26T11:06:06","date_gmt":"2023-04-26T09:06:06","guid":{"rendered":"https:\/\/omtpme.ma\/?post_type=media_presse&#038;p=26234"},"modified":"2023-11-14T11:07:58","modified_gmt":"2023-11-14T10:07:58","slug":"casablanca-settat-regroupe-387-des-entreprises-personnes-morales","status":"publish","type":"media_presse","link":"https:\/\/omtpme.ma\/en\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/","title":{"rendered":"Casablanca-Settat regroupe 38,7% des entreprises personnes morales"},"excerpt":{"rendered":"<p>La r\u00e9gion Casablanca-Settat a totalis\u00e9, en 2020, quelque 114.726 entreprises personnes morales actives (EPMA), soit 38,7% \u00e0 l&#8217;\u00e9chelle nationale&#8230;<\/p>","protected":false},"featured_media":26235,"template":"","class_list":["post-26234","media_presse","type-media_presse","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omtpme.ma\/en\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME\" \/>\n<meta property=\"og:description\" content=\"La r\u00e9gion Casablanca-Settat a totalis\u00e9, en 2020, quelque 114.726 entreprises personnes morales actives (EPMA), soit 38,7% \u00e0 l&#039;\u00e9chelle nationale...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omtpme.ma\/en\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Observatoire Marocain de la TPME - OMTPME\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T10:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OMTPME\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/\",\"url\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/\",\"name\":\"Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME\",\"isPartOf\":{\"@id\":\"https:\/\/omtpme.ma\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg\",\"datePublished\":\"2023-04-26T09:06:06+00:00\",\"dateModified\":\"2023-11-14T10:07:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage\",\"url\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg\",\"contentUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg\",\"width\":800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/omtpme.ma\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casablanca-Settat regroupe 38,7% des entreprises personnes morales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/omtpme.ma\/#website\",\"url\":\"https:\/\/omtpme.ma\/\",\"name\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"description\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"publisher\":{\"@id\":\"https:\/\/omtpme.ma\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/omtpme.ma\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/omtpme.ma\/#organization\",\"name\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"url\":\"https:\/\/omtpme.ma\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png\",\"contentUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png\",\"width\":240,\"height\":57,\"caption\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\"},\"image\":{\"@id\":\"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/\",\"https:\/\/x.com\/OMTPME\",\"https:\/\/www.linkedin.com\/company\/observatoire-marocain-de-la-tpme\/?originalSubdomain=ma\",\"https:\/\/www.instagram.com\/OMTPME\",\"https:\/\/www.youtube.com\/@OMTPME\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omtpme.ma\/en\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/","og_locale":"en_GB","og_type":"article","og_title":"Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME","og_description":"La r\u00e9gion Casablanca-Settat a totalis\u00e9, en 2020, quelque 114.726 entreprises personnes morales actives (EPMA), soit 38,7% \u00e0 l'\u00e9chelle nationale...","og_url":"https:\/\/omtpme.ma\/en\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/","og_site_name":"L&#039;Observatoire Marocain de la TPME - OMTPME","article_publisher":"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/","article_modified_time":"2023-11-14T10:07:58+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OMTPME","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/","url":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/","name":"Casablanca-Settat regroupe 38,7% des entreprises personnes morales - L&#039;Observatoire Marocain de la TPME - OMTPME","isPartOf":{"@id":"https:\/\/omtpme.ma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage"},"image":{"@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage"},"thumbnailUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg","datePublished":"2023-04-26T09:06:06+00:00","dateModified":"2023-11-14T10:07:58+00:00","breadcrumb":{"@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#primaryimage","url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg","contentUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/chef_entreprise_800.jpg","width":800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/omtpme.ma\/media_presse\/casablanca-settat-regroupe-387-des-entreprises-personnes-morales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/omtpme.ma\/"},{"@type":"ListItem","position":2,"name":"Casablanca-Settat regroupe 38,7% des entreprises personnes morales"}]},{"@type":"WebSite","@id":"https:\/\/omtpme.ma\/#website","url":"https:\/\/omtpme.ma\/","name":"L&#039;Observatoire Marocain de la TPME - OMTPME","description":"L&#039;Observatoire Marocain de la TPME - OMTPME","publisher":{"@id":"https:\/\/omtpme.ma\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omtpme.ma\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/omtpme.ma\/#organization","name":"L&#039;Observatoire Marocain de la TPME - OMTPME","url":"https:\/\/omtpme.ma\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/","url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png","contentUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png","width":240,"height":57,"caption":"L&#039;Observatoire Marocain de la TPME - OMTPME"},"image":{"@id":"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/","https:\/\/x.com\/OMTPME","https:\/\/www.linkedin.com\/company\/observatoire-marocain-de-la-tpme\/?originalSubdomain=ma","https:\/\/www.instagram.com\/OMTPME","https:\/\/www.youtube.com\/@OMTPME"]}]}},"_links":{"self":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse\/26234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse"}],"about":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/types\/media_presse"}],"version-history":[{"count":0,"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse\/26234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media\/26235"}],"wp:attachment":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media?parent=26234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}