{"id":26508,"date":"2023-05-30T10:05:03","date_gmt":"2023-05-30T08:05:03","guid":{"rendered":"https:\/\/omtpme.ma\/?post_type=media_presse&#038;p=26508"},"modified":"2023-11-27T10:08:06","modified_gmt":"2023-11-27T09:08:06","slug":"interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales","status":"publish","type":"media_presse","link":"https:\/\/omtpme.ma\/en\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/","title":{"rendered":"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb"},"excerpt":{"rendered":"<p>A l\u2019occasion de la publication de nouveaux rapports portant sur la TPE et la PME marocaine par l\u2019Observatoire marocain qui leur est d\u00e9di\u00e9, Madame Idrissi Amal, Directrice de l\u2019OMTPME, d\u00e9cortique pour nos lecteurs dans cette interview accord\u00e9e \u00e0 La Nouvelle Tribune, le travail continu et les efforts consentis pour \u00e9tablir un recensement efficace et pertinent des entreprises marocaines concern\u00e9es.<\/p>","protected":false},"featured_media":26509,"template":"","class_list":["post-26508","media_presse","type-media_presse","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omtpme.ma\/en\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME\" \/>\n<meta property=\"og:description\" content=\"A l\u2019occasion de la publication de nouveaux rapports portant sur la TPE et la PME marocaine par l\u2019Observatoire marocain qui leur est d\u00e9di\u00e9, Madame Idrissi Amal, Directrice de l\u2019OMTPME, d\u00e9cortique pour nos lecteurs dans cette interview accord\u00e9e \u00e0 La Nouvelle Tribune, le travail continu et les efforts consentis pour \u00e9tablir un recensement efficace et pertinent des entreprises marocaines concern\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omtpme.ma\/en\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Observatoire Marocain de la TPME - OMTPME\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T09:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"925\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OMTPME\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/\",\"url\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/\",\"name\":\"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME\",\"isPartOf\":{\"@id\":\"https:\/\/omtpme.ma\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg\",\"datePublished\":\"2023-05-30T08:05:03+00:00\",\"dateModified\":\"2023-11-27T09:08:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage\",\"url\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg\",\"contentUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg\",\"width\":925,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/omtpme.ma\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/omtpme.ma\/#website\",\"url\":\"https:\/\/omtpme.ma\/\",\"name\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"description\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"publisher\":{\"@id\":\"https:\/\/omtpme.ma\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/omtpme.ma\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/omtpme.ma\/#organization\",\"name\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\",\"url\":\"https:\/\/omtpme.ma\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png\",\"contentUrl\":\"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png\",\"width\":240,\"height\":57,\"caption\":\"L&#039;Observatoire Marocain de la TPME - OMTPME\"},\"image\":{\"@id\":\"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/\",\"https:\/\/x.com\/OMTPME\",\"https:\/\/www.linkedin.com\/company\/observatoire-marocain-de-la-tpme\/?originalSubdomain=ma\",\"https:\/\/www.instagram.com\/OMTPME\",\"https:\/\/www.youtube.com\/@OMTPME\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omtpme.ma\/en\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/","og_locale":"en_GB","og_type":"article","og_title":"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME","og_description":"A l\u2019occasion de la publication de nouveaux rapports portant sur la TPE et la PME marocaine par l\u2019Observatoire marocain qui leur est d\u00e9di\u00e9, Madame Idrissi Amal, Directrice de l\u2019OMTPME, d\u00e9cortique pour nos lecteurs dans cette interview accord\u00e9e \u00e0 La Nouvelle Tribune, le travail continu et les efforts consentis pour \u00e9tablir un recensement efficace et pertinent des entreprises marocaines concern\u00e9es.","og_url":"https:\/\/omtpme.ma\/en\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/","og_site_name":"L&#039;Observatoire Marocain de la TPME - OMTPME","article_publisher":"https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/","article_modified_time":"2023-11-27T09:08:06+00:00","og_image":[{"width":925,"height":430,"url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OMTPME","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/","url":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/","name":"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb - L&#039;Observatoire Marocain de la TPME - OMTPME","isPartOf":{"@id":"https:\/\/omtpme.ma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage"},"image":{"@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage"},"thumbnailUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg","datePublished":"2023-05-30T08:05:03+00:00","dateModified":"2023-11-27T09:08:06+00:00","breadcrumb":{"@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#primaryimage","url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg","contentUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2023\/11\/Image-press.jpg","width":925,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/omtpme.ma\/media_presse\/interview-de-mme-idrissi-amal-directrice-de-lomtpme-nos-rapports-permettent-devaluer-la-performance-des-tpme-et-leur-impact-sur-les-economies-regionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/omtpme.ma\/"},{"@type":"ListItem","position":2,"name":"Interview de Mme Idrissi Amal, Directrice de l\u2019OMTPME : \u00ab Nos rapports permettent d\u2019\u00e9valuer la performance des TPME et leur impact sur les \u00e9conomies r\u00e9gionales \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/omtpme.ma\/#website","url":"https:\/\/omtpme.ma\/","name":"L&#039;Observatoire Marocain de la TPME - OMTPME","description":"L&#039;Observatoire Marocain de la TPME - OMTPME","publisher":{"@id":"https:\/\/omtpme.ma\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omtpme.ma\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/omtpme.ma\/#organization","name":"L&#039;Observatoire Marocain de la TPME - OMTPME","url":"https:\/\/omtpme.ma\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/","url":"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png","contentUrl":"https:\/\/omtpme.ma\/wp-content\/uploads\/2022\/01\/cropped-logo_omtpme-13.png","width":240,"height":57,"caption":"L&#039;Observatoire Marocain de la TPME - OMTPME"},"image":{"@id":"https:\/\/omtpme.ma\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ObservatoireMarocaindelaTPME\/","https:\/\/x.com\/OMTPME","https:\/\/www.linkedin.com\/company\/observatoire-marocain-de-la-tpme\/?originalSubdomain=ma","https:\/\/www.instagram.com\/OMTPME","https:\/\/www.youtube.com\/@OMTPME"]}]}},"_links":{"self":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse\/26508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse"}],"about":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/types\/media_presse"}],"version-history":[{"count":0,"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media_presse\/26508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media\/26509"}],"wp:attachment":[{"href":"https:\/\/omtpme.ma\/en\/wp-json\/wp\/v2\/media?parent=26508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}